{"id":5772,"date":"2018-06-04T18:35:22","date_gmt":"2018-06-04T18:35:22","guid":{"rendered":"https:\/\/www.white-baos.com\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/"},"modified":"2020-09-10T07:23:33","modified_gmt":"2020-09-10T07:23:33","slug":"responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes","status":"publish","type":"post","link":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/","title":{"rendered":"Responsabilidad legal de los propietarios de perros en Espa\u00f1a. Mordeduras y accidentes."},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Consulta:<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Estimado abogado,<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nos han regalado un perro. Vivimos en una zona de campo que no est&aacute; vallada. Quisi&eacute;ramos saber si tendr&iacute;amos alguna responsabilidad en el supuesto que el perro se aleje de nuestra casa y cause alg&uacute;n problema.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Muchas gracias por su ayuda.<\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Estimado lector,<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Gracias por su consulta.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">La respuesta a su pregunta es SI. Ustedes como los propietarios del perro (o cualquier otro tipo de animal) son los responsables de todo tipo de perjuicio que su animal cause.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">La responsabilidad de los propietarios de los animales por todos los da&ntilde;os causados por &eacute;stos, se prev&eacute; expresamente en el c&oacute;digo civil espa&ntilde;ol ( Cc), en su art&iacute;culo 1905, que dice:<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\"><em>&ldquo;Art&iacute;culo 1905<\/em><\/p>\n<p style=\"text-align: justify;\"><em>El poseedor de un animal, o el que se sirve de &eacute;l, es responsable de los perjuicios que causare, aunque se le escape o extrav&iacute;e. S&oacute;lo cesar&aacute; esta responsabilidad en el caso de que el da&ntilde;o proviniera de fuerza mayor o de culpa del que lo hubiese sufrido.&rdquo;<\/em><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Este tipo de responsabilidad est&aacute; incluida en el cap&iacute;tulo del c&oacute;digo civil que trata las obligaciones que nacen con motivo de negligencias, aunque la responsabilidad en estos casos, no exige que se pruebe la negligencia del propietario del animal, pues se entiende que un due&ntilde;o de un animal diligente puede evitar que su animal cause da&ntilde;o alguno, ya sea porque lo tenga en un recinto cerrado, le coloque el bozal cuando sale a pasear, etc. Por lo tanto, siempre que un animal cause un da&ntilde;o, su propietario ser&aacute; responsable, aunque no haya sido negligente.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Son muchos los supuestos en los que los propietarios de perros y otras mascotas, pueden enfrentarse a responsabilidades por los da&ntilde;os causados por sus animales, como:<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">.-Accidentes provocados por los perros en carreteras o caminos, etc.<\/p>\n<p style=\"text-align: justify;\">.-Da&ntilde;os causados por animales en bienes ajenos.<\/p>\n<p style=\"text-align: justify;\">.- Mordeduras de perros a otros animales.<\/p>\n<p style=\"text-align: justify;\">.- Mordeduras de perros a personas.<\/p>\n<p style=\"text-align: justify;\">ETC.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Seg&uacute;n el se&ntilde;alado art&iacute;culo 1905, hay varios elementos de la responsabilidad de los propietarios y poseedores de los animales, que se deben tener en cuenta:<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">1.-&nbsp; Que ser&aacute;n responsables incluso cuando su perro o animal se haya perdido o escapado, es decir, que si se pierde un perro y este muerde a alguien, aunque no pueda el propietario impedirlo, ser&aacute; responsable.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">2.-Adem&aacute;s el due&ntilde;o del animal ser&aacute; SIEMPRE responsable, previendo la norma &uacute;nicamente dos excepciones:<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">2.1.-En casos de Fuerza Mayor, que se define como un acontecimiento extraordinario imprevisible, y que no hubiera sido posible evitar a&uacute;n aplicando la mayor diligencia. Pero lo cierto es que es muy dif&iacute;cil que se den casos de fuerza mayor, en ataques o da&ntilde;os causados por animales.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">2.2.-La otra excepci&oacute;n es cuando el hecho se haya producido por la culpa del que lo hubiese sufrido. Esta excepci&oacute;n es m&aacute;s habitual, por ejemplo, cuando alguien se acerca a un lugar donde se avisa que hay un perro peligroso, y a&uacute;n as&iacute; lo toca a trav&eacute;s de una valla y sufre una mordedura.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Si usted se encuentra en esta situaci&oacute;n, si su animal ha causado alg&uacute;n da&ntilde;o o si alg&uacute;n animal le ha causado alg&uacute;n da&ntilde;o a usted, <strong>cont&aacute;ctenos y le ayudaremos.<\/strong><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">La informaci&oacute;n proporcionada en este art&iacute;culo no pretende ser asesoramiento legal, sino que simplemente transmite la informaci&oacute;n relacionada con cuestiones legales.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Carlos Baos (Abogado)<\/p>\n<p style=\"text-align: justify;\">White &amp; Baos.<\/p>\n<p style=\"text-align: justify;\">Tel: +34 966 426 185<\/p>\n<p style=\"text-align: justify;\">E-mail: info@white-baos.com<\/p>\n<p style=\"text-align: justify;\">White &amp; Baos 2018 &#8211; Todos los Derechos Reservados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consulta: Estimado abogado, Nos han regalado un perro. Vivimos en una zona de campo que no est&aacute; vallada. Quisi&eacute;ramos saber si tendr&iacute;amos alguna responsabilidad en el supuesto que el perro se aleje de nuestra casa y cause alg&uacute;n problema. Muchas gracias por su ayuda. &nbsp; &nbsp; Estimado lector, &nbsp; Gracias por su consulta. &nbsp; La [&#8230;]<\/p>\n<p><a class=\"btn btn-primary understrap-read-more-link\" href=\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\">Leer m\u00e1s&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":520,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_crdt_document":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[381,375],"tags":[],"class_list":["post-5772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-danos-personales-accidentes-de-trafico-etc","category-judicial-derecho-civil-consumidores-y-usuarios-judicial-inmobiliario-defectos-construccion-resolucion-contratos-desahucios-comunidad-de-propietarios-etc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.<\/title>\n<meta name=\"description\" content=\"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.\" \/>\n<meta property=\"og:description\" content=\"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\" \/>\n<meta property=\"og:site_name\" content=\"White &amp; Baos, Abogados &amp; Solicitors\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-04T18:35:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-10T07:23:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carlos Baos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carlos Baos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\"},\"author\":{\"name\":\"Carlos Baos\",\"@id\":\"https:\/\/www.white-baos.com\/es\/#\/schema\/person\/f25c24bff20eb2992c5efbed4dea4bc3\"},\"headline\":\"Responsabilidad legal de los propietarios de perros en Espa\u00f1a. Mordeduras y accidentes.\",\"datePublished\":\"2018-06-04T18:35:22+00:00\",\"dateModified\":\"2020-09-10T07:23:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\"},\"wordCount\":682,\"publisher\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg\",\"articleSection\":[\"Da\u00f1os personales, accidentes de tr\u00e1fico, etc.\",\"JUDICIAL: derecho civil, consumidores y usuarios, judicial inmobiliario: defectos construcci\u00f3n, resoluci\u00f3n contratos, desahucios, comunidad de propietarios, etc.\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\",\"url\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\",\"name\":\"Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.\",\"isPartOf\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg\",\"datePublished\":\"2018-06-04T18:35:22+00:00\",\"dateModified\":\"2020-09-10T07:23:33+00:00\",\"description\":\"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage\",\"url\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg\",\"contentUrl\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.white-baos.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Responsabilidad legal de los propietarios de perros en Espa\u00f1a. Mordeduras y accidentes.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.white-baos.com\/es\/#website\",\"url\":\"https:\/\/www.white-baos.com\/es\/\",\"name\":\"White &amp; Baos, Abogados &amp; Solicitors\",\"description\":\"Anglo Spanish law firm established by both Spanish and UK lawyers based in Denia Alicante Spain\",\"publisher\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.white-baos.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.white-baos.com\/es\/#organization\",\"name\":\"White &amp; Baos, Abogados &amp; Solicitors\",\"url\":\"https:\/\/www.white-baos.com\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.white-baos.com\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2022\/09\/logo-wb-legalboutique-rojo.svg\",\"contentUrl\":\"https:\/\/www.white-baos.com\/wp-content\/uploads\/2022\/09\/logo-wb-legalboutique-rojo.svg\",\"width\":100,\"height\":100,\"caption\":\"White &amp; Baos, Abogados &amp; Solicitors\"},\"image\":{\"@id\":\"https:\/\/www.white-baos.com\/es\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.white-baos.com\/es\/#\/schema\/person\/f25c24bff20eb2992c5efbed4dea4bc3\",\"name\":\"Carlos Baos\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.","description":"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/","og_locale":"es_ES","og_type":"article","og_title":"Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.","og_description":"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.","og_url":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/","og_site_name":"White &amp; Baos, Abogados &amp; Solicitors","article_published_time":"2018-06-04T18:35:22+00:00","article_modified_time":"2020-09-10T07:23:33+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","type":"image\/jpeg"}],"author":"Carlos Baos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carlos Baos","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#article","isPartOf":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/"},"author":{"name":"Carlos Baos","@id":"https:\/\/www.white-baos.com\/es\/#\/schema\/person\/f25c24bff20eb2992c5efbed4dea4bc3"},"headline":"Responsabilidad legal de los propietarios de perros en Espa\u00f1a. Mordeduras y accidentes.","datePublished":"2018-06-04T18:35:22+00:00","dateModified":"2020-09-10T07:23:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/"},"wordCount":682,"publisher":{"@id":"https:\/\/www.white-baos.com\/es\/#organization"},"image":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","articleSection":["Da\u00f1os personales, accidentes de tr\u00e1fico, etc.","JUDICIAL: derecho civil, consumidores y usuarios, judicial inmobiliario: defectos construcci\u00f3n, resoluci\u00f3n contratos, desahucios, comunidad de propietarios, etc."],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/","url":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/","name":"Mordeduras y accidentes causados por perros en Espa\u00f1a. Responsabilidad.","isPartOf":{"@id":"https:\/\/www.white-baos.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage"},"image":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","datePublished":"2018-06-04T18:35:22+00:00","dateModified":"2020-09-10T07:23:33+00:00","description":"Derecho Espa\u00f1ol. Responsabilidad de propietarios de perros y animales. Mordeduras y accidentes.","breadcrumb":{"@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#primaryimage","url":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","contentUrl":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/www.white-baos.com\/es\/responsabilidad-legal-de-los-propietarios-de-perros-en-espana-mordeduras-y-accidentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.white-baos.com\/es\/"},{"@type":"ListItem","position":2,"name":"Responsabilidad legal de los propietarios de perros en Espa\u00f1a. Mordeduras y accidentes."}]},{"@type":"WebSite","@id":"https:\/\/www.white-baos.com\/es\/#website","url":"https:\/\/www.white-baos.com\/es\/","name":"White &amp; Baos, Abogados &amp; Solicitors","description":"Anglo Spanish law firm established by both Spanish and UK lawyers based in Denia Alicante Spain","publisher":{"@id":"https:\/\/www.white-baos.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.white-baos.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.white-baos.com\/es\/#organization","name":"White &amp; Baos, Abogados &amp; Solicitors","url":"https:\/\/www.white-baos.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.white-baos.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2022\/09\/logo-wb-legalboutique-rojo.svg","contentUrl":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2022\/09\/logo-wb-legalboutique-rojo.svg","width":100,"height":100,"caption":"White &amp; Baos, Abogados &amp; Solicitors"},"image":{"@id":"https:\/\/www.white-baos.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.white-baos.com\/es\/#\/schema\/person\/f25c24bff20eb2992c5efbed4dea4bc3","name":"Carlos Baos"}]}},"jetpack_featured_media_url":"https:\/\/www.white-baos.com\/wp-content\/uploads\/2020\/07\/dog-owners-liability-spain.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/posts\/5772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/comments?post=5772"}],"version-history":[{"count":1,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/posts\/5772\/revisions"}],"predecessor-version":[{"id":7921,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/posts\/5772\/revisions\/7921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/media\/520"}],"wp:attachment":[{"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/media?parent=5772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/categories?post=5772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.white-baos.com\/es\/wp-json\/wp\/v2\/tags?post=5772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}